{"id":5606,"date":"2021-03-23T10:54:32","date_gmt":"2021-03-23T09:54:32","guid":{"rendered":"http:\/\/www.palencia.uva.es\/wp-content\/uploads\/2021\/03\/Plantacion-olivo-Campus-Palencia-13.jpg"},"modified":"2021-03-23T10:54:32","modified_gmt":"2021-03-23T09:54:32","slug":"plantacion-olivo-campus-palencia-13-2","status":"inherit","type":"attachment","link":"http:\/\/www.palencia.uva.es\/fr\/plantacion-olivo-campus-palencia-13-2\/","title":{"rendered":"Plantaci\u00f3n-olivo-Campus-Palencia-13"},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"class_list":["post-5606","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='http:\/\/www.palencia.uva.es\/wp-content\/uploads\/2021\/03\/Plantacion-olivo-Campus-Palencia-13.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"http:\/\/www.palencia.uva.es\/wp-content\/uploads\/2021\/03\/Plantacion-olivo-Campus-Palencia-13-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":810,"height":810,"file":"2021\/03\/Plantacion-olivo-Campus-Palencia-13.jpg","sizes":{"medium":{"file":"Plantacion-olivo-Campus-Palencia-13-300x300.jpg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"http:\/\/www.palencia.uva.es\/wp-content\/uploads\/2021\/03\/Plantacion-olivo-Campus-Palencia-13-300x300.jpg"},"thumbnail":{"file":"Plantacion-olivo-Campus-Palencia-13-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"http:\/\/www.palencia.uva.es\/wp-content\/uploads\/2021\/03\/Plantacion-olivo-Campus-Palencia-13-150x150.jpg"},"medium_large":{"file":"Plantacion-olivo-Campus-Palencia-13-768x768.jpg","width":768,"height":768,"mime_type":"image\/jpeg","source_url":"http:\/\/www.palencia.uva.es\/wp-content\/uploads\/2021\/03\/Plantacion-olivo-Campus-Palencia-13-768x768.jpg"},"et-pb-post-main-image":{"file":"Plantacion-olivo-Campus-Palencia-13-400x250.jpg","width":400,"height":250,"mime_type":"image\/jpeg","source_url":"http:\/\/www.palencia.uva.es\/wp-content\/uploads\/2021\/03\/Plantacion-olivo-Campus-Palencia-13-400x250.jpg"},"et-pb-post-main-image-fullwidth":{"file":"Plantacion-olivo-Campus-Palencia-13-810x675.jpg","width":810,"height":675,"mime_type":"image\/jpeg","source_url":"http:\/\/www.palencia.uva.es\/wp-content\/uploads\/2021\/03\/Plantacion-olivo-Campus-Palencia-13-810x675.jpg"},"et-pb-portfolio-image":{"file":"Plantacion-olivo-Campus-Palencia-13-400x284.jpg","width":400,"height":284,"mime_type":"image\/jpeg","source_url":"http:\/\/www.palencia.uva.es\/wp-content\/uploads\/2021\/03\/Plantacion-olivo-Campus-Palencia-13-400x284.jpg"},"et-pb-portfolio-module-image":{"file":"Plantacion-olivo-Campus-Palencia-13-510x382.jpg","width":510,"height":382,"mime_type":"image\/jpeg","source_url":"http:\/\/www.palencia.uva.es\/wp-content\/uploads\/2021\/03\/Plantacion-olivo-Campus-Palencia-13-510x382.jpg"},"et-pb-gallery-module-image-portrait":{"file":"Plantacion-olivo-Campus-Palencia-13-400x516.jpg","width":400,"height":516,"mime_type":"image\/jpeg","source_url":"http:\/\/www.palencia.uva.es\/wp-content\/uploads\/2021\/03\/Plantacion-olivo-Campus-Palencia-13-400x516.jpg"},"et-pb-image--responsive--phone":{"file":"Plantacion-olivo-Campus-Palencia-13-480x480.jpg","width":480,"height":480,"mime_type":"image\/jpeg","source_url":"http:\/\/www.palencia.uva.es\/wp-content\/uploads\/2021\/03\/Plantacion-olivo-Campus-Palencia-13-480x480.jpg"},"full":{"file":"Plantacion-olivo-Campus-Palencia-13.jpg","width":810,"height":810,"mime_type":"image\/jpeg","source_url":"http:\/\/www.palencia.uva.es\/wp-content\/uploads\/2021\/03\/Plantacion-olivo-Campus-Palencia-13.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"http:\/\/www.palencia.uva.es\/wp-content\/uploads\/2021\/03\/Plantacion-olivo-Campus-Palencia-13.jpg","_links":{"self":[{"href":"http:\/\/www.palencia.uva.es\/fr\/wp-json\/wp\/v2\/media\/5606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.palencia.uva.es\/fr\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/www.palencia.uva.es\/fr\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/www.palencia.uva.es\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/www.palencia.uva.es\/fr\/wp-json\/wp\/v2\/comments?post=5606"}]}}